{"id":55371,"date":"2017-12-29T10:49:34","date_gmt":"2017-12-29T10:49:34","guid":{"rendered":"http:\/\/new.haciendacuatroventanas.com\/?page_id=54588"},"modified":"2023-08-01T18:30:09","modified_gmt":"2023-08-01T18:30:09","slug":"gallery","status":"publish","type":"page","link":"https:\/\/haciendalosorovales.com\/es\/gallery\/","title":{"rendered":"Galer\u00eda"},"content":{"rendered":"<div data-parent=\"true\" class=\"vc_row row-container\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-right align_right column_parent col-lg-12 container_book single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"uncont\"><span class=\"btn-container animate_when_almost_visible alpha-anim\" ><a href=\"https:\/\/betenerife.com\/accommodation\/hacienda-los-orovales-claudia\/\" class=\"custom-link btn btn-custom-typo font-377884 font-weight-600 text-uppercase  border-width-0 btn_book btn-accent btn-round btn-flat btn-shadow btn-shadow-lg btn-icon-left\" target=\"_blank\">BOOK NOW!<\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-812666\" data-row=\"script-812666\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"script-812666\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container desktop-hidden tablet-hidden mobile-hidden\"><div class=\"row single-top-padding double-bottom-padding single-h-padding full-width row-parent\" data-height-ratio=\"72\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-left align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"uncont\"><div class=\"vc_row row-internal row-container\"><div class=\"row col-no-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-8 single-internal-gutter\"><div class=\"uncol style-light shift_x_single animate_when_almost_visible left-t-right\" data-delay=\"200\"><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"column-background background-element\" style=\"opacity: 1;\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-jevc-bg\" style=\"opacity: 0.3;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"uncont\"><div class=\"uncode-single-media  text-left animate_when_almost_visible left-t-right\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"uncode-single-media-wrapper\"><img src=\"https:\/\/via.placeholder.com\/500x500.png?text=media+not+available&amp;w=500&amp;h=500\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-center align_left align_center_tablet align_center_mobile column_child col-lg-4 min_height single-internal-gutter z_index_2\"><div class=\"uncol style-light shift_y_single animate_when_almost_visible right-t-left\" data-delay=\"600\"><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"uncont\"><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text heading-bigtext\" ><h1 class=\"bigtext font-weight-100 text-accent-color\" ><span>GALER\u00cdA<\/span><\/h1><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap description\"><div class=\"heading-text el-text\" ><p class=\"h3 font-weight-300 text-color-155677-color\" ><span>Reproduzca el v\u00eddeo o haga clic en cualquiera de las im\u00e1genes para ampliar. \u00a1Disfrutar!<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-460691\" data-row=\"script-460691\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"script-460691\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row style-color-130307-bg vc_custom_1532363420358 row-container\"><div class=\"row no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"uncont\"><div class=\"vc_row row-internal row-container\"><div class=\"row col-no-gutter row-child\"><div class=\"wpb_row shift_y_half row-inner\"><div class=\"wpb_column pos-middle pos-center align_center column_child col-lg-12 no-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1532370395550 no-block-padding\"><div class=\"uncont\" style=\"max-width:50%;\"><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text heading-bigtext\" ><h2 class=\"bigtext font-weight-100 text-accent-color\" ><span>GALER\u00cdA<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row row-internal row-container\"><div class=\"row col-no-gutter row-child\"><div class=\"wpb_row shift_y_single row-inner\"><div class=\"wpb_column pos-middle pos-center align_center column_child col-lg-12 no-internal-gutter\"><div class=\"uncol style-light shift_x_double shift_y_neg_quad\" ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1532363692623 single-block-padding\"><div class=\"uncont\"><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text alpha-anim animate_when_almost_visible\" ><p class=\"h3 font-weight-300 text-color-155677-color\" ><span>Haga clic en cualquiera de las im\u00e1genes para ampliar y disfrutar!<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row style-color-130307-bg row-internal row-container\"><div class=\"row col-no-gutter row-child\"><div class=\"wpb_row row-inner row-inner-force\"><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-12 single-internal-gutter\"><div class=\"uncol style-light unexpand shift_y_neg_single animate_when_almost_visible bottom-t-top\" data-delay=\"1200\"><div class=\"uncoltable\"><div class=\"uncell no-block-padding\"><div class=\"uncont\"><div id=\"gallery-900261\" class=\"isotope-system\">\n\t\t\t\t\t\t\t<div class=\"isotope-filters menu-container half-gutter filters-inner-padding\">\n\t\t\t\t\t<div class=\"menu-horizontal limit-width menu-light text-center\">\n\t\t\t\t\t\t<ul class=\"menu-smart text-uppercase\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"filter-show-all\">\n\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<a href=\"#\" data-filter=\"*\" class=\"active\">Show all<\/a>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"filter-cat-157\"><span><a href=\"#\" data-filter=\"grid-cat-157\" class=\"\">VILLA CLAUDIA<\/a><\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"filter-cat-158\"><span><a href=\"#\" data-filter=\"grid-cat-158\" class=\"\">VILLA MARIA VICTORIA<\/a><\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"filter-cat-159\"><span><a href=\"#\" data-filter=\"grid-cat-159\" class=\"\">Exteriores<\/a><\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"isotope-wrapper half-gutter isotope-inner-padding\">\n\t\t\t\t\t\t<div class=\"isotope-container isotope-layout style-masonry\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\">\n<div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56077  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_7.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1049,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_7-300x225.jpg'\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_7-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56049  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-5.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:925,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-5-300x198.jpg'\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-5-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56088  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco-300x200.jpg'\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56090  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_plataneras.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_plataneras-300x200.jpg'\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_plataneras-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56078  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_8.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1049,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_8-300x225.jpg'\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_8-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56070  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_2-300x169.jpg'\" data-lb-index=\"5\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_2.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56051  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-7.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-7-300x200.jpg'\" data-lb-index=\"6\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-7-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56029  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3-300x200.jpg'\" data-lb-index=\"7\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56050  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-6.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-6-300x200.jpg'\" data-lb-index=\"8\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-6-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56045  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-3-300x200.jpg'\" data-lb-index=\"9\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56063  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_estanteria.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_estanteria-300x200.jpg'\" data-lb-index=\"10\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_estanteria-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56043  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cuadros-1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cuadros-1-300x200.jpg'\" data-lb-index=\"11\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cuadros-1-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56083  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-2-300x200.jpg'\" data-lb-index=\"12\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56060  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_2-300x200.jpg'\" data-lb-index=\"13\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56057  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina_2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina_2-300x200.jpg'\" data-lb-index=\"14\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina_2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56028  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_salon-3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_salon-3-300x200.jpg'\" data-lb-index=\"15\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_salon-3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56040  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_bano.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_bano-300x200.jpg'\" data-lb-index=\"16\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_bano-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56044  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-2-300x200.jpg'\" data-lb-index=\"17\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56048  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-4.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-4-300x200.jpg'\" data-lb-index=\"18\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-4-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56061  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:924,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_3-300x198.jpg'\" data-lb-index=\"19\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56059  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_1-300x200.jpg'\" data-lb-index=\"20\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_1-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56076  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_6.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_6-300x169.jpg'\" data-lb-index=\"21\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_6.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56085  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_jardinera.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_jardinera-300x200.jpg'\" data-lb-index=\"22\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_jardinera-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56073  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_4.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_4-300x169.jpg'\" data-lb-index=\"23\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_4.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56075  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_5.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_5-300x169.jpg'\" data-lb-index=\"24\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_5.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56066  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_4.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_4-300x200.jpg'\" data-lb-index=\"25\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_4-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56058  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:931,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina-300x200.jpg'\" data-lb-index=\"26\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_cocina-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56046  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-300x200.jpg'\" data-lb-index=\"27\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-2-camas-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56087  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco-3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1400,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco-3-300x300.jpg'\" data-lb-index=\"28\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_marco-3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56071  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_3-300x169.jpg'\" data-lb-index=\"29\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_3.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56091  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_sofa-2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1400,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_sofa-2-300x300.jpg'\" data-lb-index=\"30\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_sofa-2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56089  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_pernaculo.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1261,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_pernaculo-300x270.jpg'\" data-lb-index=\"31\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_pernaculo-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56082  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamaca.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamaca-300x200.jpg'\" data-lb-index=\"32\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamaca-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56081  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras-300x200.jpg'\" data-lb-index=\"33\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56079  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_balcon.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_balcon-300x200.jpg'\" data-lb-index=\"34\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_balcon-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56041  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_BARROTES-2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_BARROTES-2-300x200.jpg'\" data-lb-index=\"35\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_BARROTES-2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56042  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cocina_2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cocina_2-300x200.jpg'\" data-lb-index=\"36\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_cocina_2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56052  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_escritorio.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_escritorio-300x200.jpg'\" data-lb-index=\"37\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_escritorio-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56084  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-3-300x200.jpg'\" data-lb-index=\"38\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_hamacas-3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56074  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_04.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1048,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_04-300x225.jpg'\" data-lb-index=\"39\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_04-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56065  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3-1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3-1-300x200.jpg'\" data-lb-index=\"40\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_3-1-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56064  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_1-300x200.jpg'\" data-lb-index=\"41\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_salon_1-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56080  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras-2.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras-2-300x200.jpg'\" data-lb-index=\"42\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_exterior_fachada-con-plataneras-2-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56067  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_vista-ventana.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_vista-ventana-300x200.jpg'\" data-lb-index=\"43\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_vista-ventana-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56054  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_VISTA-VENTANA.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_VISTA-VENTANA-300x200.jpg'\" data-lb-index=\"44\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_VISTA-VENTANA-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56072  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_03.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:1048,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_03-300x225.jpg'\" data-lb-index=\"45\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/HACIENDA_LOS_OROVALES_03-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56047  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-3.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:916,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-3-300x196.jpg'\" data-lb-index=\"46\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_dormitorio-principal-3-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56056  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_bano.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_bano-300x200.jpg'\" data-lb-index=\"47\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_bano-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56069  grid-cat-159 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:787,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_1-300x169.jpg'\" data-lb-index=\"48\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2022\/10\/hacienda_los_orovales_1.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56053  grid-cat-158 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_SALON-1.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_SALON-1-300x200.jpg'\" data-lb-index=\"49\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_maria_victoria_SALON-1-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-middle tmb-overlay-text-left tmb-text-space-reduced tmb-bordered tmb-id-56062  grid-cat-157 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\">\n\t\t\t\t\t\t<div class=\"t-inside\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.2%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_4.jpg\" class=\"pushed\" data-skin=\"white\" data-social=\"1\" data-lbox=\"ilightbox_gallery-900261\" data-options=\"width:1400,height:933,thumbnail: 'https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_4-300x200.jpg'\" data-lb-index=\"50\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-accent-bg\" style=\"opacity: 0.01;\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><\/div><\/div><\/div><\/div><img src=\"https:\/\/haciendalosorovales.com\/wp-content\/uploads\/2019\/11\/hacienda_los_orovales_villa_claudia_dormitorio_4-uai-1400x787.jpg\" width=\"1400\" height=\"787\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row row-internal row-container desktop-hidden tablet-hidden mobile-hidden\"><div class=\"row col-no-gutter row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_center column_child col-lg-12 no-internal-gutter\"><div class=\"uncol style-light shift_y_quad\" ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1532363356881 no-block-padding\"><div class=\"uncont\" style=\"max-width:50%;\"><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text heading-bigtext\" ><h2 class=\"bigtext font-weight-100 text-accent-color\" ><span>INSTAGRAM<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p>[instagram-feed user=&#8221;haciendaelcardon&#8221;]<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-467067\" data-row=\"script-467067\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"script-467067\"));<\/script><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"BOOK NOW! GALLERYPlay the video or click on any of the images to enlarge. Enjoy!GALLERYClick on any of the images [...]","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"_links":{"self":[{"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/pages\/55371"}],"collection":[{"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/comments?post=55371"}],"version-history":[{"count":18,"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/pages\/55371\/revisions"}],"predecessor-version":[{"id":56155,"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/pages\/55371\/revisions\/56155"}],"wp:attachment":[{"href":"https:\/\/haciendalosorovales.com\/es\/wp-json\/wp\/v2\/media?parent=55371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}